{"id":7901,"date":"2023-11-28T13:22:49","date_gmt":"2023-11-28T12:22:49","guid":{"rendered":"https:\/\/www.asf-brandenburg.de\/asf_wp\/?p=7901"},"modified":"2023-12-04T13:26:48","modified_gmt":"2023-12-04T12:26:48","slug":"am-nikolaustag-adventsfest-im-albert-schweitzer-haus-mit-feuershow-stars-ravenchild","status":"publish","type":"post","link":"https:\/\/www.asf-brandenburg.de\/asf_wp\/aktuelles\/2023\/am-nikolaustag-adventsfest-im-albert-schweitzer-haus-mit-feuershow-stars-ravenchild\/","title":{"rendered":"Am Nikolaustag: Adventsfest im Albert-Schweitzer-Haus mit Feuershow-Stars Ravenchild"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p><strong>Spremberg.<\/strong> Das Albert-Schweitzer-Familienwerk Brandenburg unterst\u00fctzt den Lebendigen Adventskalender der Stadt Spremberg und \u00f6ffnet in diesem Jahr das T\u00fcrchen mit der Nummer 6 im Albert-Schweitzer-Haus und auf dem Hof der Tafel Spremberg. Beteiligt sind die Teams der Fr\u00fchf\u00f6rder- und Beratungsstelle, des Offenen Jugendtreffs, der Tafel Spremberg und der Kinderchor des Albert-Schweitzer-Familienwerks Brandenburg sowie die BQS D\u00f6bern.<\/p>\n<p><strong>Herzliche Einladung zum Adventsfest am Nikolaustag<\/strong><\/p>\n<p>Auf dem geschm\u00fcckten Hof des Tafelgel\u00e4ndes in der Gartenstra\u00dfe 9 gibt es am 06. Dezember <strong>zwischen 16 und 18 Uhr <\/strong>zum Mitmachen:<\/p>\n<ul>\n<li>Bastelwerkstatt und Pl\u00e4tzchenb\u00e4ckerei f\u00fcr Kinder<\/li>\n<li>Kreativfabrik mit Basteln f\u00fcr Erwachsene<\/li>\n<\/ul>\n<p>Show und Spektakel:<\/p>\n<ul>\n<li>16 Uhr: Weihnachtliches auf die Ohren mit dem neuen Kinderchor des Albert-Schweitzer-Familienwerks Brandenburg<\/li>\n<li>17.30 Uhr: spektakul\u00e4re Feuershow mit den Eventstars Ravenchild-Fire<\/li>\n<li>Besuch vom Weihnachtsmann und seinen Gehilfen<\/li>\n<\/ul>\n<p>Weihnachtliches f\u00fcr den Bauch:<\/p>\n<ul>\n<li>Lagerfeuer mit Stockbrot<\/li>\n<li>Suppe und Grillstation<\/li>\n<li>Gl\u00fchwein, Kinderpunsch, Gebackenes, Kaffee und Kuchen<\/li>\n<\/ul>\n<p><strong>Teilerl\u00f6s der Einnahmen kommt Spremberger Initiative gegen Einsamkeit zugute<\/strong><\/p>\n<p>Der Eintritt ist frei und Menschen aller Nationen sind willkommen. Ein Teilerl\u00f6s der Einnahmen f\u00fcr die Verk\u00f6stigung spendet der Verein der Initiative gegen Einsamkeit\u00a0\u00a0 &#8222;WeihnachtsPL\u00c4TZCHEN \u2013 Wer Weihnachten nicht allein sein m\u00f6chte findet bei uns einen Platz&#8220; der \u00d6rtlichen Liga Spremberg und der Michaelkirche. Auch das spendenfinanzierte Weihnachtsmobil soll am 24. Dezember wieder verschiedene Stationen in Spremberg anfahren und Anlaufpunkt f\u00fcr alle Menschen sein, die Heiligabend nicht in Gesellschaft verbringen k\u00f6nnen. Die Gesch\u00e4ftsf\u00fchrung Kerstin Nowka und Kai Noack freuen sich dar\u00fcber, zu diesem Anlass einladen und unterst\u00fctzen zu d\u00fcrfen:<\/p>\n<blockquote>\n<p><em>\u201eF\u00fcr uns als sozialer Tr\u00e4ger beginnt mit der Adventszeit auch die Saison, in der wir m\u00f6glichst viele Angebote des Miteinanders schaffen m\u00f6chten <\/em>\u2013<em> und das m\u00f6glichst kostenfrei. Denn Einsamkeit, Isolation und finanzielle N\u00f6te schlie\u00dfen Menschen vom gesellschaftlichen Leben aus, das k\u00f6nnen wir jeden Tag in unseren Tafeln und bei der Arbeit unserer Erziehungshilfen erleben. Aber niemand sollte Weihnachten alleine verbringen m\u00fcssen! Daher finden wir Aktionen wie das Weihnachtsmobil an Heiligabend besonders unterst\u00fctzungsbed\u00fcrftig und hoffen, beim Adventsnachmittag einen gro\u00dfen Beitrag f\u00fcr den Spendentopf sammeln zu k\u00f6nnen.\u201c<\/em><\/p>\n<\/blockquote>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"212\" height=\"300\" title=\"Adventsfest_06. T\u00fcrchen\" src=\"https:\/\/www.asf-brandenburg.de\/asf_wp\/wp-content\/uploads\/2023\/12\/Adventsfest_06.-Tuerchen-212x300.jpg\" alt class=\"img-responsive wp-image-7903\" srcset=\"https:\/\/www.asf-brandenburg.de\/asf_wp\/wp-content\/uploads\/2023\/12\/Adventsfest_06.-Tuerchen-200x283.jpg 200w, https:\/\/www.asf-brandenburg.de\/asf_wp\/wp-content\/uploads\/2023\/12\/Adventsfest_06.-Tuerchen-400x566.jpg 400w, https:\/\/www.asf-brandenburg.de\/asf_wp\/wp-content\/uploads\/2023\/12\/Adventsfest_06.-Tuerchen-600x849.jpg 600w, https:\/\/www.asf-brandenburg.de\/asf_wp\/wp-content\/uploads\/2023\/12\/Adventsfest_06.-Tuerchen-800x1131.jpg 800w, https:\/\/www.asf-brandenburg.de\/asf_wp\/wp-content\/uploads\/2023\/12\/Adventsfest_06.-Tuerchen-1200x1697.jpg 1200w, https:\/\/www.asf-brandenburg.de\/asf_wp\/wp-content\/uploads\/2023\/12\/Adventsfest_06.-Tuerchen-scaled.jpg 1810w\" sizes=\"(max-width: 1280px) 100vw, (max-width: 770px) 100vw, 800px\" \/><\/span><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Das Albert-Schweitzer-Familienwerk Brandenburg unterst\u00fctzt den Lebendigen Adventskalender der Stadt Spremberg und \u00f6ffnet in diesem Jahr das T\u00fcrchen mit der Nummer 6 im Albert-Schweitzer-Haus und auf dem Hof der Tafel Spremberg. Beteiligt sind die Teams der Fr\u00fchf\u00f6rder- und Beratungsstelle, des Offenen Jugendtreffs, der Tafel Spremberg und der Kinderchor des Albert-Schweitzer-Familienwerks Brandenburg sowie die BQS D\u00f6bern. <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-7901","post","type-post","status-publish","format-standard","hentry","category-neuigkeiten-2019"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Am Nikolaustag: Adventsfest im Albert-Schweitzer-Haus mit Feuershow-Stars Ravenchild - Albert-Schweitzer-Familienwerk Brandenburg e.V.<\/title>\n<meta name=\"description\" content=\"Das Albert-Schweitzer-Familienwerk Brandenburg unterst\u00fctzt den Lebendigen Adventskalender der Stadt Spremberg und \u00f6ffnet in diesem Jahr das T\u00fcrchen mit der Nummer 6 im Albert-Schweitzer-Haus und auf dem Hof der Tafel Spremberg. Beteiligt sind die Teams der Fr\u00fchf\u00f6rder- und Beratungsstelle, des Offenen Jugendtreffs, der Tafel Spremberg und der Kinderchor des Albert-Schweitzer-Familienwerks Brandenburg sowie die BQS D\u00f6bern.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asf-brandenburg.de\/asf_wp\/aktuelles\/2023\/am-nikolaustag-adventsfest-im-albert-schweitzer-haus-mit-feuershow-stars-ravenchild\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Am Nikolaustag: Adventsfest im Albert-Schweitzer-Haus mit Feuershow-Stars Ravenchild - Albert-Schweitzer-Familienwerk Brandenburg e.V.\" \/>\n<meta property=\"og:description\" content=\"Das Albert-Schweitzer-Familienwerk Brandenburg unterst\u00fctzt den Lebendigen Adventskalender der Stadt Spremberg und \u00f6ffnet in diesem Jahr das T\u00fcrchen mit der Nummer 6 im Albert-Schweitzer-Haus und auf dem Hof der Tafel Spremberg. Beteiligt sind die Teams der Fr\u00fchf\u00f6rder- und Beratungsstelle, des Offenen Jugendtreffs, der Tafel Spremberg und der Kinderchor des Albert-Schweitzer-Familienwerks Brandenburg sowie die BQS D\u00f6bern.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asf-brandenburg.de\/asf_wp\/aktuelles\/2023\/am-nikolaustag-adventsfest-im-albert-schweitzer-haus-mit-feuershow-stars-ravenchild\/\" \/>\n<meta property=\"og:site_name\" content=\"Albert-Schweitzer-Familienwerk Brandenburg e.V.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AlbertSchweitzerFamilienwerkBrandenburg\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-28T12:22:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-04T12:26:48+00:00\" \/>\n<meta name=\"author\" content=\"Web Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Web Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/aktuelles\\\/2023\\\/am-nikolaustag-adventsfest-im-albert-schweitzer-haus-mit-feuershow-stars-ravenchild\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/aktuelles\\\/2023\\\/am-nikolaustag-adventsfest-im-albert-schweitzer-haus-mit-feuershow-stars-ravenchild\\\/\"},\"author\":{\"name\":\"Web Admin\",\"@id\":\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/#\\\/schema\\\/person\\\/a63ba1553f2aa75f90f3809d9e4a1efc\"},\"headline\":\"Am Nikolaustag: Adventsfest im Albert-Schweitzer-Haus mit Feuershow-Stars Ravenchild\",\"datePublished\":\"2023-11-28T12:22:49+00:00\",\"dateModified\":\"2023-12-04T12:26:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/aktuelles\\\/2023\\\/am-nikolaustag-adventsfest-im-albert-schweitzer-haus-mit-feuershow-stars-ravenchild\\\/\"},\"wordCount\":2028,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/#organization\"},\"articleSection\":[\"Neuigkeiten 2019\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/aktuelles\\\/2023\\\/am-nikolaustag-adventsfest-im-albert-schweitzer-haus-mit-feuershow-stars-ravenchild\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/aktuelles\\\/2023\\\/am-nikolaustag-adventsfest-im-albert-schweitzer-haus-mit-feuershow-stars-ravenchild\\\/\",\"url\":\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/aktuelles\\\/2023\\\/am-nikolaustag-adventsfest-im-albert-schweitzer-haus-mit-feuershow-stars-ravenchild\\\/\",\"name\":\"Am Nikolaustag: Adventsfest im Albert-Schweitzer-Haus mit Feuershow-Stars Ravenchild - Albert-Schweitzer-Familienwerk Brandenburg e.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/#website\"},\"datePublished\":\"2023-11-28T12:22:49+00:00\",\"dateModified\":\"2023-12-04T12:26:48+00:00\",\"description\":\"Das Albert-Schweitzer-Familienwerk Brandenburg unterst\u00fctzt den Lebendigen Adventskalender der Stadt Spremberg und \u00f6ffnet in diesem Jahr das T\u00fcrchen mit der Nummer 6 im Albert-Schweitzer-Haus und auf dem Hof der Tafel Spremberg. Beteiligt sind die Teams der Fr\u00fchf\u00f6rder- und Beratungsstelle, des Offenen Jugendtreffs, der Tafel Spremberg und der Kinderchor des Albert-Schweitzer-Familienwerks Brandenburg sowie die BQS D\u00f6bern.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/aktuelles\\\/2023\\\/am-nikolaustag-adventsfest-im-albert-schweitzer-haus-mit-feuershow-stars-ravenchild\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/aktuelles\\\/2023\\\/am-nikolaustag-adventsfest-im-albert-schweitzer-haus-mit-feuershow-stars-ravenchild\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/aktuelles\\\/2023\\\/am-nikolaustag-adventsfest-im-albert-schweitzer-haus-mit-feuershow-stars-ravenchild\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Am Nikolaustag: Adventsfest im Albert-Schweitzer-Haus mit Feuershow-Stars Ravenchild\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/#website\",\"url\":\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/\",\"name\":\"Albert-Schweitzer-Kinderd\u00f6rfer und Familienwerke Brandenburg e. V.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/#organization\",\"name\":\"Albert-Schweitzer-Familienwerk Brandenburg e. V.\",\"url\":\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/Logo_ASF_BRB_318x107.png\",\"contentUrl\":\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/Logo_ASF_BRB_318x107.png\",\"width\":318,\"height\":107,\"caption\":\"Albert-Schweitzer-Familienwerk Brandenburg e. V.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AlbertSchweitzerFamilienwerkBrandenburg\",\"https:\\\/\\\/www.youtube.com\\\/@asfbrandenburg\",\"https:\\\/\\\/www.instagram.com\\\/asf_brandenburg\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/#\\\/schema\\\/person\\\/a63ba1553f2aa75f90f3809d9e4a1efc\",\"name\":\"Web Admin\",\"sameAs\":[\"http:\\\/\\\/www.asf-brandenburg.de\"],\"url\":\"https:\\\/\\\/www.asf-brandenburg.de\\\/asf_wp\\\/aktuelles\\\/author\\\/asf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Am Nikolaustag: Adventsfest im Albert-Schweitzer-Haus mit Feuershow-Stars Ravenchild - Albert-Schweitzer-Familienwerk Brandenburg e.V.","description":"Das Albert-Schweitzer-Familienwerk Brandenburg unterst\u00fctzt den Lebendigen Adventskalender der Stadt Spremberg und \u00f6ffnet in diesem Jahr das T\u00fcrchen mit der Nummer 6 im Albert-Schweitzer-Haus und auf dem Hof der Tafel Spremberg. Beteiligt sind die Teams der Fr\u00fchf\u00f6rder- und Beratungsstelle, des Offenen Jugendtreffs, der Tafel Spremberg und der Kinderchor des Albert-Schweitzer-Familienwerks Brandenburg sowie die BQS D\u00f6bern.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asf-brandenburg.de\/asf_wp\/aktuelles\/2023\/am-nikolaustag-adventsfest-im-albert-schweitzer-haus-mit-feuershow-stars-ravenchild\/","og_locale":"de_DE","og_type":"article","og_title":"Am Nikolaustag: Adventsfest im Albert-Schweitzer-Haus mit Feuershow-Stars Ravenchild - Albert-Schweitzer-Familienwerk Brandenburg e.V.","og_description":"Das Albert-Schweitzer-Familienwerk Brandenburg unterst\u00fctzt den Lebendigen Adventskalender der Stadt Spremberg und \u00f6ffnet in diesem Jahr das T\u00fcrchen mit der Nummer 6 im Albert-Schweitzer-Haus und auf dem Hof der Tafel Spremberg. Beteiligt sind die Teams der Fr\u00fchf\u00f6rder- und Beratungsstelle, des Offenen Jugendtreffs, der Tafel Spremberg und der Kinderchor des Albert-Schweitzer-Familienwerks Brandenburg sowie die BQS D\u00f6bern.","og_url":"https:\/\/www.asf-brandenburg.de\/asf_wp\/aktuelles\/2023\/am-nikolaustag-adventsfest-im-albert-schweitzer-haus-mit-feuershow-stars-ravenchild\/","og_site_name":"Albert-Schweitzer-Familienwerk Brandenburg e.V.","article_publisher":"https:\/\/www.facebook.com\/AlbertSchweitzerFamilienwerkBrandenburg","article_published_time":"2023-11-28T12:22:49+00:00","article_modified_time":"2023-12-04T12:26:48+00:00","author":"Web Admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Web Admin","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.asf-brandenburg.de\/asf_wp\/aktuelles\/2023\/am-nikolaustag-adventsfest-im-albert-schweitzer-haus-mit-feuershow-stars-ravenchild\/#article","isPartOf":{"@id":"https:\/\/www.asf-brandenburg.de\/asf_wp\/aktuelles\/2023\/am-nikolaustag-adventsfest-im-albert-schweitzer-haus-mit-feuershow-stars-ravenchild\/"},"author":{"name":"Web Admin","@id":"https:\/\/www.asf-brandenburg.de\/asf_wp\/#\/schema\/person\/a63ba1553f2aa75f90f3809d9e4a1efc"},"headline":"Am Nikolaustag: Adventsfest im Albert-Schweitzer-Haus mit Feuershow-Stars Ravenchild","datePublished":"2023-11-28T12:22:49+00:00","dateModified":"2023-12-04T12:26:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.asf-brandenburg.de\/asf_wp\/aktuelles\/2023\/am-nikolaustag-adventsfest-im-albert-schweitzer-haus-mit-feuershow-stars-ravenchild\/"},"wordCount":2028,"commentCount":0,"publisher":{"@id":"https:\/\/www.asf-brandenburg.de\/asf_wp\/#organization"},"articleSection":["Neuigkeiten 2019"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.asf-brandenburg.de\/asf_wp\/aktuelles\/2023\/am-nikolaustag-adventsfest-im-albert-schweitzer-haus-mit-feuershow-stars-ravenchild\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.asf-brandenburg.de\/asf_wp\/aktuelles\/2023\/am-nikolaustag-adventsfest-im-albert-schweitzer-haus-mit-feuershow-stars-ravenchild\/","url":"https:\/\/www.asf-brandenburg.de\/asf_wp\/aktuelles\/2023\/am-nikolaustag-adventsfest-im-albert-schweitzer-haus-mit-feuershow-stars-ravenchild\/","name":"Am Nikolaustag: Adventsfest im Albert-Schweitzer-Haus mit Feuershow-Stars Ravenchild - Albert-Schweitzer-Familienwerk Brandenburg e.V.","isPartOf":{"@id":"https:\/\/www.asf-brandenburg.de\/asf_wp\/#website"},"datePublished":"2023-11-28T12:22:49+00:00","dateModified":"2023-12-04T12:26:48+00:00","description":"Das Albert-Schweitzer-Familienwerk Brandenburg unterst\u00fctzt den Lebendigen Adventskalender der Stadt Spremberg und \u00f6ffnet in diesem Jahr das T\u00fcrchen mit der Nummer 6 im Albert-Schweitzer-Haus und auf dem Hof der Tafel Spremberg. Beteiligt sind die Teams der Fr\u00fchf\u00f6rder- und Beratungsstelle, des Offenen Jugendtreffs, der Tafel Spremberg und der Kinderchor des Albert-Schweitzer-Familienwerks Brandenburg sowie die BQS D\u00f6bern.","breadcrumb":{"@id":"https:\/\/www.asf-brandenburg.de\/asf_wp\/aktuelles\/2023\/am-nikolaustag-adventsfest-im-albert-schweitzer-haus-mit-feuershow-stars-ravenchild\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asf-brandenburg.de\/asf_wp\/aktuelles\/2023\/am-nikolaustag-adventsfest-im-albert-schweitzer-haus-mit-feuershow-stars-ravenchild\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.asf-brandenburg.de\/asf_wp\/aktuelles\/2023\/am-nikolaustag-adventsfest-im-albert-schweitzer-haus-mit-feuershow-stars-ravenchild\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.asf-brandenburg.de\/asf_wp\/"},{"@type":"ListItem","position":2,"name":"Am Nikolaustag: Adventsfest im Albert-Schweitzer-Haus mit Feuershow-Stars Ravenchild"}]},{"@type":"WebSite","@id":"https:\/\/www.asf-brandenburg.de\/asf_wp\/#website","url":"https:\/\/www.asf-brandenburg.de\/asf_wp\/","name":"Albert-Schweitzer-Kinderd\u00f6rfer und Familienwerke Brandenburg e. V.","description":"","publisher":{"@id":"https:\/\/www.asf-brandenburg.de\/asf_wp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asf-brandenburg.de\/asf_wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.asf-brandenburg.de\/asf_wp\/#organization","name":"Albert-Schweitzer-Familienwerk Brandenburg e. V.","url":"https:\/\/www.asf-brandenburg.de\/asf_wp\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.asf-brandenburg.de\/asf_wp\/#\/schema\/logo\/image\/","url":"https:\/\/www.asf-brandenburg.de\/asf_wp\/wp-content\/uploads\/2018\/08\/Logo_ASF_BRB_318x107.png","contentUrl":"https:\/\/www.asf-brandenburg.de\/asf_wp\/wp-content\/uploads\/2018\/08\/Logo_ASF_BRB_318x107.png","width":318,"height":107,"caption":"Albert-Schweitzer-Familienwerk Brandenburg e. V."},"image":{"@id":"https:\/\/www.asf-brandenburg.de\/asf_wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AlbertSchweitzerFamilienwerkBrandenburg","https:\/\/www.youtube.com\/@asfbrandenburg","https:\/\/www.instagram.com\/asf_brandenburg\/"]},{"@type":"Person","@id":"https:\/\/www.asf-brandenburg.de\/asf_wp\/#\/schema\/person\/a63ba1553f2aa75f90f3809d9e4a1efc","name":"Web Admin","sameAs":["http:\/\/www.asf-brandenburg.de"],"url":"https:\/\/www.asf-brandenburg.de\/asf_wp\/aktuelles\/author\/asf\/"}]}},"_links":{"self":[{"href":"https:\/\/www.asf-brandenburg.de\/asf_wp\/wp-json\/wp\/v2\/posts\/7901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asf-brandenburg.de\/asf_wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asf-brandenburg.de\/asf_wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asf-brandenburg.de\/asf_wp\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asf-brandenburg.de\/asf_wp\/wp-json\/wp\/v2\/comments?post=7901"}],"version-history":[{"count":0,"href":"https:\/\/www.asf-brandenburg.de\/asf_wp\/wp-json\/wp\/v2\/posts\/7901\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.asf-brandenburg.de\/asf_wp\/wp-json\/wp\/v2\/media?parent=7901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asf-brandenburg.de\/asf_wp\/wp-json\/wp\/v2\/categories?post=7901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asf-brandenburg.de\/asf_wp\/wp-json\/wp\/v2\/tags?post=7901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}